{"id":7349,"date":"2021-11-30T19:00:11","date_gmt":"2021-11-30T19:00:11","guid":{"rendered":"https:\/\/cancortada.com\/?page_id=7349"},"modified":"2022-02-14T12:00:02","modified_gmt":"2022-02-14T12:00:02","slug":"esdeveniments-corporatius","status":"publish","type":"page","link":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/","title":{"rendered":"Esdeveniments corporatius"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7349\" class=\"elementor elementor-7349 elementor-7348\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-efe5bee eltdf-elementor-row-grid-section elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle eltdf-parallax-row-no eltdf-content-aligment-left eltdf-disabled-bg-image-bellow-no\" data-id=\"efe5bee\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-013e350\" data-id=\"013e350\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-926ebef text-blanc-titol elementor-widget elementor-widget-eltdf_section_title\" data-id=\"926ebef\" data-element_type=\"widget\" data-widget_type=\"eltdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"eltdf-section-title-holder    \" style=\"text-align: center\">\n\t<div class=\"eltdf-st-inner\">\n        \t\t            <div class=\"eltdf-st-title-holder\">\n                                <h1 class=\"eltdf-st-title\" >\n                    Esdeveniments corporatius                <\/h1>\n                            <\/div>\n\t\t\t\t\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-c42c570 eltdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default eltdf-parallax-row-no eltdf-content-aligment-left eltdf-disabled-bg-image-bellow-no\" data-id=\"c42c570\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da5d026\" data-id=\"da5d026\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5246b2 elementor-widget elementor-widget-text-editor\" data-id=\"d5246b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tConvencions, presentacions, jornades de treball, activitats de teaming i sopars d\u2019empresa.\n\nLes empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.\n<br><br>\nA <strong>Can Cortada<\/strong> disposem d\u00b4espais diferents envoltats d\u00b4un entorn natural \u00fanic. Els espais interiors s\u00f3n polivalents i poden comptar amb equipament audiovisual.\n<br><br>\nPoden optar per cockatils de peu, presentacions i showcooking amb la participaci\u00f3 dels assistents.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-ad61707 elementor-section-full_width elementor-section-height-default elementor-section-height-default eltdf-parallax-row-no eltdf-content-aligment-left eltdf-elementor-row-grid-no eltdf-disabled-bg-image-bellow-no\" data-id=\"ad61707\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-065f1f9\" data-id=\"065f1f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-168199f elementor-widget elementor-widget-qi_addons_for_elementor_image_slider\" data-id=\"168199f\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-slider qodef-qi-fslightbox-popup qodef-popup-gallery qodef-col-num--3 qodef-qi-grid qodef-qi-swiper-container qodef-navigation--inside qodef-navigation--hover-move\" data-options=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;slidesPerView&quot;:&quot;3&quot;,&quot;spaceBetween&quot;:30,&quot;spaceBetweenTablet&quot;:30,&quot;spaceBetweenMobile&quot;:30,&quot;effect&quot;:&quot;&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;centeredSlides&quot;:false,&quot;speed&quot;:&quot;&quot;,&quot;speedAnimation&quot;:&quot;5000&quot;,&quot;outsideNavigation&quot;:&quot;no&quot;,&quot;outsidePagination&quot;:&quot;no&quot;,&quot;unique&quot;:108,&quot;partialValue&quot;:0,&quot;disablePartialValue&quot;:&quot;&quot;,&quot;parallax&quot;:&quot;no&quot;}\">\n\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1709\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg 2560w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-300x200.jpg 300w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-1024x684.jpg 1024w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-768x513.jpg 768w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-1536x1025.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0046-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1709\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0046-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0046-scaled.jpg 2560w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0046-300x200.jpg 300w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0046-1024x684.jpg 1024w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0046-768x513.jpg 768w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0046-1536x1025.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/58.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"827\" height=\"1225\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/58.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/58.jpg 827w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/58-203x300.jpg 203w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/58-691x1024.jpg 691w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/58-768x1138.jpg 768w\" sizes=\"(max-width: 827px) 100vw, 827px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/59.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"827\" height=\"502\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/59.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/59.jpg 827w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/59-300x182.jpg 300w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/59-768x466.jpg 768w\" sizes=\"(max-width: 827px) 100vw, 827px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/barca-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/barca-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/barca-scaled.jpg 2560w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/barca-300x225.jpg 300w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/barca-1024x768.jpg 1024w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/barca-768x576.jpg 768w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/barca-1536x1152.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/caballos.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"438\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/caballos.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/caballos.jpg 800w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/caballos-300x164.jpg 300w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/caballos-768x420.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/castells.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"199\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/castells.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/castells.jpg 338w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/castells-300x177.jpg 300w\" sizes=\"(max-width: 338px) 100vw, 338px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_0951-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_0951-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_0951-scaled.jpg 2560w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_0951-300x225.jpg 300w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_0951-1024x768.jpg 1024w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_0951-768x576.jpg 768w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_0951-1536x1152.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_1974-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_1974-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_1974-scaled.jpg 1920w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_1974-225x300.jpg 225w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_1974-768x1024.jpg 768w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_1974-1152x1536.jpg 1152w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_1974-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_3651-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_3651-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_3651-scaled.jpg 1920w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_3651-225x300.jpg 225w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_3651-768x1024.jpg 768w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_3651-1152x1536.jpg 1152w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_3651-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_5892-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_5892-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_5892-scaled.jpg 2560w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_5892-300x225.jpg 300w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_5892-1024x768.jpg 1024w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_5892-768x576.jpg 768w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/IMG_5892-1536x1152.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"qodef-e swiper-slide\">\n\t<div class=\"qodef-e-inner\">\n\t\t<div class=\"qodef-e-inner-holder\">\n\t\t\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/ZRSXSR_10-scaled.jpg\" data-type=\"image\" data-fslightbox=\"gallery-108\" data-e-disable-page-transition=\u201dtrue\u201d>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/ZRSXSR_10-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/ZRSXSR_10-scaled.jpg 2560w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/ZRSXSR_10-300x200.jpg 300w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/ZRSXSR_10-1024x683.jpg 1024w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/ZRSXSR_10-768x512.jpg 768w, https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/ZRSXSR_10-1536x1024.jpg 1536w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\t<\/div>\n\t\t<div class=\"swiper-button-prev\"><svg class=\"qodef-swiper-arrow-left\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewBox=\"0 0 34.2 32.3\" xml:space=\"preserve\" style=\"stroke-width: 2;\"><line x1=\"0.5\" y1=\"16\" x2=\"33.5\" y2=\"16\"\/><line x1=\"0.3\" y1=\"16.5\" x2=\"16.2\" y2=\"0.7\"\/><line x1=\"0\" y1=\"15.4\" x2=\"16.2\" y2=\"31.6\"\/><\/svg><\/div>\n\t<div class=\"swiper-button-next\"><svg class=\"qodef-swiper-arrow-right\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" viewBox=\"0 0 34.2 32.3\" xml:space=\"preserve\" style=\"stroke-width: 2;\"><line x1=\"0\" y1=\"16\" x2=\"33\" y2=\"16\"\/><line x1=\"17.3\" y1=\"0.7\" x2=\"33.2\" y2=\"16.5\"\/><line x1=\"17.3\" y1=\"31.6\" x2=\"33.5\" y2=\"15.4\"\/><\/svg><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-28be390 elementor-section-boxed elementor-section-height-default elementor-section-height-default eltdf-parallax-row-no eltdf-content-aligment-left eltdf-elementor-row-grid-no eltdf-disabled-bg-image-bellow-no\" data-id=\"28be390\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d203fc2\" data-id=\"d203fc2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd27c96 title-responsive elementor-widget elementor-widget-eltdf_section_title\" data-id=\"cd27c96\" data-element_type=\"widget\" data-widget_type=\"eltdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"eltdf-section-title-holder    \" style=\"text-align: center\">\n\t<div class=\"eltdf-st-inner\">\n        \t\t            <div class=\"eltdf-st-title-holder\">\n                                    <div class=\"decor\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41.125\" height=\"9.146\">\n                            <path fill=\"none\" stroke=\"#9C7C57\" stroke-miterlimit=\"10\" d=\"M40.881 8.576L20.562.591.244 8.576\"\/>\n                            <path fill=\"none\" stroke=\"#9C7C57\" stroke-miterlimit=\"10\" d=\"M40.881.591L20.562 8.576.243.591\"\/>\n                        <\/svg><\/div>\n                                <h1 class=\"eltdf-st-title\" >\n                    Formulari de contacte                <\/h1>\n                                    <div class=\"decor\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41.125\" height=\"9.146\">\n                            <path fill=\"none\" stroke=\"#9C7C57\" stroke-miterlimit=\"10\" d=\"M40.881 8.576L20.562.591.244 8.576\"\/>\n                            <path fill=\"none\" stroke=\"#9C7C57\" stroke-miterlimit=\"10\" d=\"M40.881.591L20.562 8.576.243.591\"\/>\n                        <\/svg><\/div>\n                            <\/div>\n\t\t\t\t\t\t\t<p class=\"eltdf-st-text\" >\n\t\t\t\tPer contactar o sol\u00b7licitar m\u00e9s informaci\u00f3 sobre els nostres serveis, ompliu el seg\u00fcent formulari\t\t\t<\/p>\n\t\t\t\t\t<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beb2dce elementor-widget elementor-widget-eltdf_cf7\" data-id=\"beb2dce\" data-element_type=\"widget\" data-widget_type=\"eltdf_cf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7463-o1\" lang=\"ca\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ca\/wp-json\/wp\/v2\/pages\/7349#wpcf7-f7463-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulari de contacte\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"7463\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.8\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ca\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7463-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<label> Persona de contacte*\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n\n<label>Tel\u00e8fon*\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-704\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-704\" \/><\/span><\/label>\n\n<label> Data*\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date-580\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date-580\" \/><\/span><\/label>\n\n<label> Comensals*\n<span class=\"wpcf7-form-control-wrap\" data-name=\"comensales\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"comensales\" \/><\/span><\/label>\n\n<label> E-mail*\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\n<label> Comentaris*\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-761\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-761\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He llegit i accepto la <a href=\"\/ca\/politica-de-privacitat\" target=\"_blank\">Pol\u00edtica de privacitat<\/a><\/span><\/label><\/span><\/span><\/span>\n<br>\n<button class=\"wpcf7-form-control wpcf7-submit eltdf-btn eltdf-btn-medium eltdf-btn-outline\" type=\"submit\"><span class=\"eltdf-btn-text\">Enviar<\/span><\/button>\n\n*Camps obligatoris<p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"230\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Esdeveniments corporatius Convencions, presentacions, jornades de treball, activitats de teaming i sopars d\u2019empresa. Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable. A Can Cortada disposem d\u00b4espais diferents envoltats d\u00b4un entorn natural \u00fanic. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esdeveniments corporatius - Can Cortada<\/title>\n<meta name=\"description\" content=\"Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esdeveniments corporatius\" \/>\n<meta property=\"og:description\" content=\"Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/\" \/>\n<meta property=\"og:site_name\" content=\"Can Cortada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cancortada\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-14T12:00:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/CJ_030.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"447\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Esdeveniments corporatius\" \/>\n<meta name=\"twitter:description\" content=\"Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/CJ_030.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/\",\"url\":\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/\",\"name\":\"Esdeveniments corporatius - Can Cortada\",\"isPartOf\":{\"@id\":\"https:\/\/cancortada.com\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg\",\"datePublished\":\"2021-11-30T19:00:11+00:00\",\"dateModified\":\"2022-02-14T12:00:02+00:00\",\"description\":\"Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.\",\"breadcrumb\":{\"@id\":\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#primaryimage\",\"url\":\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg\",\"contentUrl\":\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cancortada.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments corporatius\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cancortada.com\/ca\/#website\",\"url\":\"https:\/\/cancortada.com\/ca\/\",\"name\":\"Can Cortada\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cancortada.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cancortada.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cancortada.com\/ca\/#organization\",\"name\":\"Can Cortada\",\"url\":\"https:\/\/cancortada.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/cancortada.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/09\/logo.png\",\"contentUrl\":\"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/09\/logo.png\",\"width\":241,\"height\":241,\"caption\":\"Can Cortada\"},\"image\":{\"@id\":\"https:\/\/cancortada.com\/ca\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cancortada\/\",\"https:\/\/www.instagram.com\/cancortada\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esdeveniments corporatius - Can Cortada","description":"Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/","og_locale":"ca_ES","og_type":"article","og_title":"Esdeveniments corporatius","og_description":"Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.","og_url":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/","og_site_name":"Can Cortada","article_publisher":"https:\/\/www.facebook.com\/cancortada\/","article_modified_time":"2022-02-14T12:00:02+00:00","og_image":[{"width":670,"height":447,"url":"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/CJ_030.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Esdeveniments corporatius","twitter_description":"Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.","twitter_image":"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/CJ_030.jpg","twitter_misc":{"Temps estimat de lectura":"8 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/","url":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/","name":"Esdeveniments corporatius - Can Cortada","isPartOf":{"@id":"https:\/\/cancortada.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#primaryimage"},"image":{"@id":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#primaryimage"},"thumbnailUrl":"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg","datePublished":"2021-11-30T19:00:11+00:00","dateModified":"2022-02-14T12:00:02+00:00","description":"Les empreses busquen als esdeveniments corporatius assolir els objectius marcats en un entorn emblem\u00e0tic i favorable.","breadcrumb":{"@id":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#primaryimage","url":"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg","contentUrl":"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/11\/0044-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cancortada.com\/ca\/esdeveniments-corporatius\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cancortada.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments corporatius"}]},{"@type":"WebSite","@id":"https:\/\/cancortada.com\/ca\/#website","url":"https:\/\/cancortada.com\/ca\/","name":"Can Cortada","description":"","publisher":{"@id":"https:\/\/cancortada.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cancortada.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/cancortada.com\/ca\/#organization","name":"Can Cortada","url":"https:\/\/cancortada.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/cancortada.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/09\/logo.png","contentUrl":"https:\/\/cancortada.com\/wp-content\/uploads\/2021\/09\/logo.png","width":241,"height":241,"caption":"Can Cortada"},"image":{"@id":"https:\/\/cancortada.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cancortada\/","https:\/\/www.instagram.com\/cancortada"]}]}},"_links":{"self":[{"href":"https:\/\/cancortada.com\/ca\/wp-json\/wp\/v2\/pages\/7349"}],"collection":[{"href":"https:\/\/cancortada.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cancortada.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cancortada.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cancortada.com\/ca\/wp-json\/wp\/v2\/comments?post=7349"}],"version-history":[{"count":0,"href":"https:\/\/cancortada.com\/ca\/wp-json\/wp\/v2\/pages\/7349\/revisions"}],"wp:attachment":[{"href":"https:\/\/cancortada.com\/ca\/wp-json\/wp\/v2\/media?parent=7349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}